{"id":41637,"date":"2026-04-22T14:06:09","date_gmt":"2026-04-22T11:06:09","guid":{"rendered":"https:\/\/cardboard-expert.com\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/"},"modified":"2026-04-22T14:06:09","modified_gmt":"2026-04-22T11:06:09","slug":"polygonal-boxes-hexagonal-security-buckles-mockup-188100","status":"publish","type":"product","link":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/","title":{"rendered":"Polygonal boxes hexagonal security buckles mockup 188100"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":41639,"template":"","meta":[],"product_brand":[],"product_cat":[5000,5010,5017,5003],"product_tag":[],"class_list":{"0":"post-41637","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boxes","7":"product_cat-food-packaging","8":"product_cat-food-packaging-others","9":"product_cat-boxes-polygonal-box","10":"pa_modelid-1508","12":"first","13":"instock","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Polygonal boxes hexagonal security buckles mockup 188100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polygonal boxes hexagonal security buckles mockup 188100\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/\" \/>\n<meta property=\"og:site_name\" content=\"cardboard-expert.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/packexpertou\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cardboard-expert.com\/wp-content\/uploads\/2026\/04\/mockup-188100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/\",\"url\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/\",\"name\":\"Polygonal boxes hexagonal security buckles mockup 188100\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cardboard-expert.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/mockup-188100.jpg\",\"datePublished\":\"2026-04-22T11:06:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cardboard-expert.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/mockup-188100.jpg\",\"contentUrl\":\"https:\\\/\\\/cardboard-expert.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/mockup-188100.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Polygonal boxes hexagonal security buckles mockup 188100\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/product\\\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Polygonal boxes hexagonal security buckles mockup 188100\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/\",\"name\":\"cardboard-expert.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/#organization\",\"name\":\"cardboard-expert.com\",\"url\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cardboard-expert.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo_white.webp\",\"contentUrl\":\"https:\\\/\\\/cardboard-expert.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo_white.webp\",\"width\":2000,\"height\":550,\"caption\":\"cardboard-expert.com\"},\"image\":{\"@id\":\"https:\\\/\\\/cardboard-expert.com\\\/no\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/packexpertou\",\"https:\\\/\\\/www.instagram.com\\\/packexpertoufiliale\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pack-expert-ou\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/packexpert\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@packexpert\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polygonal boxes hexagonal security buckles mockup 188100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/","og_locale":"nb_NO","og_type":"article","og_title":"Polygonal boxes hexagonal security buckles mockup 188100","og_url":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/","og_site_name":"cardboard-expert.com","article_publisher":"https:\/\/www.facebook.com\/packexpertou","og_image":[{"width":1920,"height":1920,"url":"https:\/\/cardboard-expert.com\/wp-content\/uploads\/2026\/04\/mockup-188100.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/","url":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/","name":"Polygonal boxes hexagonal security buckles mockup 188100","isPartOf":{"@id":"https:\/\/cardboard-expert.com\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/#primaryimage"},"image":{"@id":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/#primaryimage"},"thumbnailUrl":"https:\/\/cardboard-expert.com\/wp-content\/uploads\/2026\/04\/mockup-188100.jpg","datePublished":"2026-04-22T11:06:09+00:00","breadcrumb":{"@id":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/"]}]},{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/#primaryimage","url":"https:\/\/cardboard-expert.com\/wp-content\/uploads\/2026\/04\/mockup-188100.jpg","contentUrl":"https:\/\/cardboard-expert.com\/wp-content\/uploads\/2026\/04\/mockup-188100.jpg","width":1920,"height":1920,"caption":"Polygonal boxes hexagonal security buckles mockup 188100"},{"@type":"BreadcrumbList","@id":"https:\/\/cardboard-expert.com\/no\/product\/polygonal-boxes-hexagonal-security-buckles-mockup-188100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/cardboard-expert.com\/no\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/cardboard-expert.com\/no\/shop\/"},{"@type":"ListItem","position":3,"name":"Polygonal boxes hexagonal security buckles mockup 188100"}]},{"@type":"WebSite","@id":"https:\/\/cardboard-expert.com\/no\/#website","url":"https:\/\/cardboard-expert.com\/no\/","name":"cardboard-expert.com","description":"","publisher":{"@id":"https:\/\/cardboard-expert.com\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardboard-expert.com\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/cardboard-expert.com\/no\/#organization","name":"cardboard-expert.com","url":"https:\/\/cardboard-expert.com\/no\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/cardboard-expert.com\/no\/#\/schema\/logo\/image\/","url":"https:\/\/cardboard-expert.com\/wp-content\/uploads\/2023\/06\/logo_white.webp","contentUrl":"https:\/\/cardboard-expert.com\/wp-content\/uploads\/2023\/06\/logo_white.webp","width":2000,"height":550,"caption":"cardboard-expert.com"},"image":{"@id":"https:\/\/cardboard-expert.com\/no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/packexpertou","https:\/\/www.instagram.com\/packexpertoufiliale\/","https:\/\/www.linkedin.com\/company\/pack-expert-ou\/","https:\/\/www.pinterest.com\/packexpert\/","https:\/\/www.youtube.com\/@packexpert"]}]}},"_links":{"self":[{"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/product\/41637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/product\/41637\/revisions"}],"predecessor-version":[{"id":41638,"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/product\/41637\/revisions\/41638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/media\/41639"}],"wp:attachment":[{"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/media?parent=41637"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/product_brand?post=41637"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/product_cat?post=41637"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cardboard-expert.com\/no\/wp-json\/wp\/v2\/product_tag?post=41637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}